{"id":8712,"date":"2023-02-26T11:51:08","date_gmt":"2023-02-26T10:51:08","guid":{"rendered":"https:\/\/dikcg.me\/wpold\/?p=8712"},"modified":"2023-03-01T11:50:28","modified_gmt":"2023-03-01T10:50:28","slug":"saziv-za-88-sjednicu-2","status":"publish","type":"post","link":"https:\/\/dikcg.me\/wpold\/saziv-za-88-sjednicu-2\/","title":{"rendered":"Saziv za 88. sjednicu"},"content":{"rendered":"<p><a href=\"https:\/\/dikcg.me\/wpold\/wp-content\/uploads\/2023\/02\/Saziv-88.pdf\">Saziv za 88. sjednicu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Saziv za 88. sjednicu","protected":false},"author":56,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[246],"_links":{"self":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8712"}],"collection":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/comments?post=8712"}],"version-history":[{"count":1,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8712\/revisions"}],"predecessor-version":[{"id":8715,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8712\/revisions\/8715"}],"wp:attachment":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/media?parent=8712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/categories?post=8712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/tags?post=8712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}