{"id":8630,"date":"2023-02-23T15:20:54","date_gmt":"2023-02-23T14:20:54","guid":{"rendered":"https:\/\/dikcg.me\/wpold\/?p=8630"},"modified":"2023-02-24T22:49:03","modified_gmt":"2023-02-24T21:49:03","slug":"saziv-za-85-sjednicu-2","status":"publish","type":"post","link":"https:\/\/dikcg.me\/wpold\/saziv-za-85-sjednicu-2\/","title":{"rendered":"Saziv za 85. sjednicu"},"content":{"rendered":"<p><a href=\"https:\/\/dikcg.me\/wpold\/wp-content\/uploads\/2023\/02\/Saziv-85.pdf\">Saziv za 85. sjednicu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Saziv za 85. sjednicu","protected":false},"author":56,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[246],"_links":{"self":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8630"}],"collection":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/comments?post=8630"}],"version-history":[{"count":1,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8630\/revisions"}],"predecessor-version":[{"id":8633,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/posts\/8630\/revisions\/8633"}],"wp:attachment":[{"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/media?parent=8630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/categories?post=8630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dikcg.me\/wpold\/wp-json\/wp\/v2\/tags?post=8630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}